{"id":2192,"date":"2018-06-28T09:21:19","date_gmt":"2018-06-28T12:21:19","guid":{"rendered":"http:\/\/axionlift.com\/?p=974"},"modified":"2022-05-31T14:37:05","modified_gmt":"2022-05-31T14:37:05","slug":"alta-performance-alcance","status":"publish","type":"post","link":"https:\/\/axionlift.com\/es\/alta-performance-alcance\/","title":{"rendered":"Alta performance, a su alcance"},"content":{"rendered":"\n\t\t<div id=\"fws_6a579aafefa35\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<p>Desde <strong><span class=\"nombre\">AxionLift<\/span>, Elevadores e Hidrogr\u00faas<\/strong> tenemos como lema y frase de cabecera \u201calta performance a su alcance\u201d. Nuestros clientes pueden atestiguarlo con su propia experiencia, pero esta vez hemos cre\u00eddo conveniente explicarlo nosotros mismos. Consideramos que es necesario realizar una divisi\u00f3n de este slogan en dos partes, y por un lado hablar de lo que nos convierte en una empresa de alta performance, y por otro, de qu\u00e9 manera estamos siempre a su alcance. Que mejor forma de hacerlo, que empezar por el coraz\u00f3n de <span class=\"nombre\">AxionLift<\/span>: nuestros productos.<\/p>\n<p>Por un lado, hablamos de <strong>\u201calta performance\u201d<\/strong> cuando nos referimos a nuestros elevadores e hidrogr\u00faas, que han sido dise\u00f1ados y construidos para brindarle un rendimiento superior a lo largo del tiempo. Todos los equipos son fabricados con materiales de la mejor calidad, que garantizan la \u00f3ptima funcionalidad y duraci\u00f3n de los equipos, entre los cuales se destacan los aceros livianos de alta resistencia, comandos hidr\u00e1ulicos y v\u00e1lvulas provenientes de Italia, as\u00ed como mangueras y sellos de Estados Unidos.<\/p>\n<p>En nuestras plantas productivas, tanto las ubicadas en San Francisco, C\u00f3rdoba, como la radicada en Indaiatuba, S\u00e3o Paulo, apostamos a la innovaci\u00f3n permanente. Por eso implementamos un proceso productivo altamente tecnificado, donde utilizamos soldadura robotizada y sistemas de vanguardia que van desde el dise\u00f1o hasta la construcci\u00f3n y el montaje. El cuidado y la atenci\u00f3n sobre toda la producci\u00f3n son garant\u00eda de confianza y durabilidad para nuestros clientes.<\/p>\n<p>Por otro lado, hablamos de estar <strong>\u201ca su alcance\u201d<\/strong> porque estamos cerca de nuestros clientes, brindando un soporte integral con personal especializado, que incluye desde asesoramiento comercial y montaje de equipos, hasta servicio t\u00e9cnico y capacitaci\u00f3n. De esta manera aseguramos la eficiencia y operatividad de los equipos, dando respuesta r\u00e1pida y efectiva a todas sus consultas.<\/p>\n<p>Para estar m\u00e1s cerca de nuestros clientes y mejorar cada vez m\u00e1s nuestros tiempos de respuesta, estamos ubicados en cuatro puntos estrat\u00e9gicos para nuestro sector: Buenos Aires, C\u00f3rdoba, Neuqu\u00e9n y San Pablo. En estos centros de servicio los clientes pueden encontrar un stock permanente de repuestos durante todo el a\u00f1o, y ser atendidos por personal t\u00e9cnico calificado y altamente capacitado.<\/p>\n<p><span class=\"nombre\">AxionLift<\/span> no solo asegura la mejor calidad en equipos de fabricaci\u00f3n nacional sino que adem\u00e1s est\u00e1 siempre cerca del cliente cuando \u00e9ste lo necesita, disponible y listo para responder a sus necesidades. Decimos, entonces, que somos alta performance a su alcance no solo por la calidad de nuestro producto final, sino tambi\u00e9n por la excelencia de nuestros procesos productivos, la atenci\u00f3n de nuestros servicios y el trabajo diario de nuestro equipo humano que hay detr\u00e1s de cada producto terminado.<\/p>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"Desde AxionLift, Elevadores e Hidrogr\u00faas tenemos como lema y frase de cabecera \u201calta performance a su alcance\u201d. Nuestros clientes pueden atestiguarlo con su propia experiencia, pero esta vez hemos cre\u00eddo...","protected":false},"author":2,"featured_media":2253,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52],"tags":[],"wf_post_folders":[80],"class_list":["post-2192","post","type-post","status-publish","format-standard","has-post-thumbnail","category-fabricacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alta performance, a su alcance - AxionLift - Elevadores &amp; Hidrogr\u00faas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/axionlift.com\/es\/alta-performance-alcance\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alta performance, a su alcance - AxionLift - Elevadores &amp; Hidrogr\u00faas\" \/>\n<meta property=\"og:url\" content=\"http:\/\/axionlift.com\/es\/alta-performance-alcance\/\" \/>\n<meta property=\"og:site_name\" content=\"AxionLift - Elevadores &amp; Hidrogr\u00faas\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-28T12:21:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-31T14:37:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/axionlift.com\/wp-content\/uploads\/2018\/06\/AXION-Imagen-para-NOTA-en-BLOG-01-20180628.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"975\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AXION | Elevadores &amp; Hidrogr\u00faas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AXION | Elevadores &amp; Hidrogr\u00faas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/axionlift.com\\\/pt\\\/alta-performance-alcance\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/axionlift.com\\\/pt\\\/alta-performance-alcance\\\/\"},\"author\":{\"name\":\"AXION | Elevadores &amp; Hidrogr\u00faas\",\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/#\\\/schema\\\/person\\\/acea9f5e5baf6f17d3bb576b786fd5c8\"},\"headline\":\"Alta performance, a su alcance\",\"datePublished\":\"2018-06-28T12:21:19+00:00\",\"dateModified\":\"2022-05-31T14:37:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/axionlift.com\\\/pt\\\/alta-performance-alcance\\\/\"},\"wordCount\":615,\"publisher\":{\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/axionlift.com\\\/pt\\\/alta-performance-alcance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/axionlift.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/AXION-Imagen-para-NOTA-en-BLOG-01-20180628.jpg\",\"articleSection\":[\"Fabricaci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/axionlift.com\\\/pt\\\/alta-performance-alcance\\\/\",\"url\":\"http:\\\/\\\/axionlift.com\\\/pt\\\/alta-performance-alcance\\\/\",\"name\":\"Alta performance, a su alcance - AxionLift - Elevadores &amp; Hidrogr\u00faas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/axionlift.com\\\/pt\\\/alta-performance-alcance\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/axionlift.com\\\/pt\\\/alta-performance-alcance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/axionlift.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/AXION-Imagen-para-NOTA-en-BLOG-01-20180628.jpg\",\"datePublished\":\"2018-06-28T12:21:19+00:00\",\"dateModified\":\"2022-05-31T14:37:05+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/axionlift.com\\\/pt\\\/alta-performance-alcance\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/axionlift.com\\\/pt\\\/alta-performance-alcance\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/axionlift.com\\\/pt\\\/alta-performance-alcance\\\/#primaryimage\",\"url\":\"https:\\\/\\\/axionlift.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/AXION-Imagen-para-NOTA-en-BLOG-01-20180628.jpg\",\"contentUrl\":\"https:\\\/\\\/axionlift.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/AXION-Imagen-para-NOTA-en-BLOG-01-20180628.jpg\",\"width\":975,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/axionlift.com\\\/pt\\\/alta-performance-alcance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/axionlift.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alta performance, a su alcance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/axionlift.com\\\/en\\\/\",\"name\":\"AxionLift - Elevadores & Hidrogr\u00faas\",\"description\":\"AxionLift - Una organizaci\u00f3n de alta performance\",\"publisher\":{\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/#organization\"},\"alternateName\":\"AxionLift\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/axionlift.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/#organization\",\"name\":\"AxionLift - Elevadores & Hidrogr\u00faas\",\"alternateName\":\"AxionLift\",\"url\":\"https:\\\/\\\/axionlift.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/axionlift.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/axion-mini.jpg\",\"contentUrl\":\"https:\\\/\\\/axionlift.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/axion-mini.jpg\",\"width\":320,\"height\":320,\"caption\":\"AxionLift - Elevadores & Hidrogr\u00faas\"},\"image\":{\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/#\\\/schema\\\/person\\\/acea9f5e5baf6f17d3bb576b786fd5c8\",\"name\":\"AXION | Elevadores &amp; Hidrogr\u00faas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4bb0cdeb5f63fa57308758ad6e5d2366a845a65bbe64212fed18c0987756f646?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4bb0cdeb5f63fa57308758ad6e5d2366a845a65bbe64212fed18c0987756f646?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4bb0cdeb5f63fa57308758ad6e5d2366a845a65bbe64212fed18c0987756f646?s=96&d=mm&r=g\",\"caption\":\"AXION | Elevadores &amp; Hidrogr\u00faas\"},\"url\":\"https:\\\/\\\/axionlift.com\\\/es\\\/author\\\/axion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alta performance, a su alcance - AxionLift - Elevadores &amp; Hidrogr\u00faas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/axionlift.com\/es\/alta-performance-alcance\/","og_locale":"es_ES","og_type":"article","og_title":"Alta performance, a su alcance - AxionLift - Elevadores &amp; Hidrogr\u00faas","og_url":"http:\/\/axionlift.com\/es\/alta-performance-alcance\/","og_site_name":"AxionLift - Elevadores &amp; Hidrogr\u00faas","article_published_time":"2018-06-28T12:21:19+00:00","article_modified_time":"2022-05-31T14:37:05+00:00","og_image":[{"width":975,"height":500,"url":"https:\/\/axionlift.com\/wp-content\/uploads\/2018\/06\/AXION-Imagen-para-NOTA-en-BLOG-01-20180628.jpg","type":"image\/jpeg"}],"author":"AXION | Elevadores &amp; Hidrogr\u00faas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"AXION | Elevadores &amp; Hidrogr\u00faas","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/axionlift.com\/pt\/alta-performance-alcance\/#article","isPartOf":{"@id":"http:\/\/axionlift.com\/pt\/alta-performance-alcance\/"},"author":{"name":"AXION | Elevadores &amp; Hidrogr\u00faas","@id":"https:\/\/axionlift.com\/en\/#\/schema\/person\/acea9f5e5baf6f17d3bb576b786fd5c8"},"headline":"Alta performance, a su alcance","datePublished":"2018-06-28T12:21:19+00:00","dateModified":"2022-05-31T14:37:05+00:00","mainEntityOfPage":{"@id":"http:\/\/axionlift.com\/pt\/alta-performance-alcance\/"},"wordCount":615,"publisher":{"@id":"https:\/\/axionlift.com\/en\/#organization"},"image":{"@id":"http:\/\/axionlift.com\/pt\/alta-performance-alcance\/#primaryimage"},"thumbnailUrl":"https:\/\/axionlift.com\/wp-content\/uploads\/2018\/06\/AXION-Imagen-para-NOTA-en-BLOG-01-20180628.jpg","articleSection":["Fabricaci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"http:\/\/axionlift.com\/pt\/alta-performance-alcance\/","url":"http:\/\/axionlift.com\/pt\/alta-performance-alcance\/","name":"Alta performance, a su alcance - AxionLift - Elevadores &amp; Hidrogr\u00faas","isPartOf":{"@id":"https:\/\/axionlift.com\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/axionlift.com\/pt\/alta-performance-alcance\/#primaryimage"},"image":{"@id":"http:\/\/axionlift.com\/pt\/alta-performance-alcance\/#primaryimage"},"thumbnailUrl":"https:\/\/axionlift.com\/wp-content\/uploads\/2018\/06\/AXION-Imagen-para-NOTA-en-BLOG-01-20180628.jpg","datePublished":"2018-06-28T12:21:19+00:00","dateModified":"2022-05-31T14:37:05+00:00","breadcrumb":{"@id":"http:\/\/axionlift.com\/pt\/alta-performance-alcance\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/axionlift.com\/pt\/alta-performance-alcance\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/axionlift.com\/pt\/alta-performance-alcance\/#primaryimage","url":"https:\/\/axionlift.com\/wp-content\/uploads\/2018\/06\/AXION-Imagen-para-NOTA-en-BLOG-01-20180628.jpg","contentUrl":"https:\/\/axionlift.com\/wp-content\/uploads\/2018\/06\/AXION-Imagen-para-NOTA-en-BLOG-01-20180628.jpg","width":975,"height":500},{"@type":"BreadcrumbList","@id":"http:\/\/axionlift.com\/pt\/alta-performance-alcance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/axionlift.com\/"},{"@type":"ListItem","position":2,"name":"Alta performance, a su alcance"}]},{"@type":"WebSite","@id":"https:\/\/axionlift.com\/en\/#website","url":"https:\/\/axionlift.com\/en\/","name":"AxionLift - Elevadores & Hidrogr\u00faas","description":"AxionLift - Una organizaci\u00f3n de alta performance","publisher":{"@id":"https:\/\/axionlift.com\/en\/#organization"},"alternateName":"AxionLift","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/axionlift.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/axionlift.com\/en\/#organization","name":"AxionLift - Elevadores & Hidrogr\u00faas","alternateName":"AxionLift","url":"https:\/\/axionlift.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/axionlift.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/axionlift.com\/wp-content\/uploads\/2024\/08\/axion-mini.jpg","contentUrl":"https:\/\/axionlift.com\/wp-content\/uploads\/2024\/08\/axion-mini.jpg","width":320,"height":320,"caption":"AxionLift - Elevadores & Hidrogr\u00faas"},"image":{"@id":"https:\/\/axionlift.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/axionlift.com\/en\/#\/schema\/person\/acea9f5e5baf6f17d3bb576b786fd5c8","name":"AXION | Elevadores &amp; Hidrogr\u00faas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4bb0cdeb5f63fa57308758ad6e5d2366a845a65bbe64212fed18c0987756f646?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4bb0cdeb5f63fa57308758ad6e5d2366a845a65bbe64212fed18c0987756f646?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4bb0cdeb5f63fa57308758ad6e5d2366a845a65bbe64212fed18c0987756f646?s=96&d=mm&r=g","caption":"AXION | Elevadores &amp; Hidrogr\u00faas"},"url":"https:\/\/axionlift.com\/es\/author\/axion\/"}]}},"_links":{"self":[{"href":"https:\/\/axionlift.com\/es\/wp-json\/wp\/v2\/posts\/2192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axionlift.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/axionlift.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/axionlift.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/axionlift.com\/es\/wp-json\/wp\/v2\/comments?post=2192"}],"version-history":[{"count":2,"href":"https:\/\/axionlift.com\/es\/wp-json\/wp\/v2\/posts\/2192\/revisions"}],"predecessor-version":[{"id":3358,"href":"https:\/\/axionlift.com\/es\/wp-json\/wp\/v2\/posts\/2192\/revisions\/3358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/axionlift.com\/es\/wp-json\/wp\/v2\/media\/2253"}],"wp:attachment":[{"href":"https:\/\/axionlift.com\/es\/wp-json\/wp\/v2\/media?parent=2192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/axionlift.com\/es\/wp-json\/wp\/v2\/categories?post=2192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/axionlift.com\/es\/wp-json\/wp\/v2\/tags?post=2192"},{"taxonomy":"wf_post_folders","embeddable":true,"href":"https:\/\/axionlift.com\/es\/wp-json\/wp\/v2\/wf_post_folders?post=2192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}