{"id":2016,"date":"2021-11-26T13:21:41","date_gmt":"2021-11-26T16:21:41","guid":{"rendered":"https:\/\/axionlift.com\/?p=2016"},"modified":"2022-05-31T13:35:44","modified_gmt":"2022-05-31T13:35:44","slug":"cuales-las-certificaciones-elevadores-e-hidrogruas","status":"publish","type":"post","link":"https:\/\/axionlift.com\/en\/cuales-las-certificaciones-elevadores-e-hidrogruas\/","title":{"rendered":"\u00bfCu\u00e1les son las certificaciones de nuestros elevadores e hidrogr\u00faas?"},"content":{"rendered":"<div id=\"fws_6a577ee8c57e7\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<p>Nuestros elevadores e hidrogr\u00faas <span class=\"nombre\">AxionLift<\/span> est\u00e1n certificados por las normas de calidad internacionales <a class=\"enlace-entrada\" href=\"http:\/\/www.itvalledelguadiana.edu.mx\/ftp\/Normas%20ISO\/ISO%209001-2015%20Sistemas%20de%20Gesti%C3%B3n%20de%20la%20Calidad.pdf\">ISO 9001<\/a>\u00a0y\u00a0<a class=\"enlace-entrada\" href=\"https:\/\/vdocuments.mx\/ansi-922-1990pdf.html?page=1\">ANSI A92.2<\/a>. Hoy queremos hablarles de que significa que un equipo est\u00e9 certificado internacionalmente, y que beneficios tiene para el usuario.<\/p>\n<p>Primero nos referiremos a la norma ISO 9001, que establece los requisitos que debe cumplir una empresa para tener un correcto sistema de gesti\u00f3n de calidad en su sistema productivo. Aqu\u00ed se pone el foco sobre el cliente, y su satisfacci\u00f3n se pone en primer lugar.<\/p>\n<p>Para un operario, que los equipos con los que trabaja est\u00e9n certificados por la norma ISO 9001 significa que el producto cumple con los m\u00e1s altos est\u00e1ndares de calidad en lo que se refiere a producci\u00f3n y testeo. La normativa exige implementar t\u00e9cnicas de trabajo m\u00e1s definidas y eficaces, con lo que no solo se minimiza el n\u00famero de errores en la fabricaci\u00f3n, tambi\u00e9n se trabaja m\u00e1s r\u00e1pido y mejor ahorrando dinero y recursos. Esto permite incrementar la calidad de los productos y servicios y con ella, la satisfacci\u00f3n de los clientes. As\u00ed pueden tener la certeza de que nuestro equipo tendr\u00e1 el m\u00e1ximo rendimiento y una vida \u00fatil m\u00e1s larga.<\/p>\n<p>Refiri\u00e9ndonos ahora a la norma ANSI 92.2, esta norma establece los est\u00e1ndares que deben cumplir, entre otros equipos, los hidroelevadores o elevadores hidr\u00e1ulicos, en materia t\u00e9cnica y de seguridad. Peri\u00f3dicamente estas normas se actualizan con nuevas condiciones, que tienen el objetivo de aumentar la seguridad de los operarios. Esto incluye requisitos que deben cumplir los equipos para una operaci\u00f3n segura, por ejemplo:<\/p>\n<ul>\n<li>Comandos en barquilla y en la base,<\/li>\n<li>Sistema de nivelaci\u00f3n de barquilla autom\u00e1tico<\/li>\n<li>Sistema interlock de los estabilizadores: sistema de seguridad que no permite operar sin que los estabilizadores est\u00e9n apoyados en el piso. Este sistema es obligatorio desde la versi\u00f3n 2015.<\/li>\n<li>Cobertores para equipos aislados: A partir de la versi\u00f3n 2015, se aumentaron los requisitos en los cobertores para aumentar la protecci\u00f3n del operario.<\/li>\n<\/ul>\n<p>Desde <span class=\"nombre\">AxionLift<\/span> mantenemos nuestros equipos actualizados para garantizarle una operaci\u00f3n segura para el operario. Trabajar con elevadores o hidrogr\u00faas certificados por normas internacionales le brinda la tranquilidad de saber que su equipo fue fabricado siguiendo estrictos requisitos de calidad y testeo, y que cuenta con los \u00faltimos componentes y accesorios para facilitar y hacer siempre m\u00e1s productivo su trabajo.<\/p>\n<p><strong><span class=\"nombre\">AxionLift<\/span>, Alta performance a su alcance.<\/strong><\/p>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"Nuestros elevadores e hidrogr\u00faas AxionLift est\u00e1n certificados por las normas de calidad internacionales ISO 9001\u00a0y\u00a0ANSI A92.2. Hoy queremos hablarles de que significa que un equipo est\u00e9 certificado internacionalmente, y que...","protected":false},"author":2,"featured_media":2363,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52,53],"tags":[],"wf_post_folders":[80],"class_list":["post-2016","post","type-post","status-publish","format-standard","has-post-thumbnail","category-fabricacion","category-innovacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfCu\u00e1les son las certificaciones de nuestros elevadores e hidrogr\u00faas?<\/title>\n<meta name=\"description\" content=\"Nuestros elevadores e hidrogr\u00faas AXION est\u00e1n certificados por las normas de calidad internacionales ISO 9001\u00a0y\u00a0ANSI A92.2\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/axionlift.com\/en\/cuales-las-certificaciones-elevadores-e-hidrogruas\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1les son las certificaciones de nuestros elevadores e hidrogr\u00faas?\" \/>\n<meta property=\"og:description\" content=\"Nuestros elevadores e hidrogr\u00faas AXION est\u00e1n certificados por las normas de calidad internacionales ISO 9001\u00a0y\u00a0ANSI A92.2\" \/>\n<meta property=\"og:url\" content=\"https:\/\/axionlift.com\/en\/cuales-las-certificaciones-elevadores-e-hidrogruas\/\" \/>\n<meta property=\"og:site_name\" content=\"AxionLift - Elevadores &amp; Hidrogr\u00faas\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-26T16:21:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-31T13:35:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/axionlift.com\/wp-content\/uploads\/2021\/11\/20211126-Blog-Nota-CERTIFICACIONES.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"975\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AXION | Elevadores &amp; Hidrogr\u00faas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"AXION | Elevadores &amp; Hidrogr\u00faas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/cuales-las-certificaciones-elevadores-e-hidrogruas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/cuales-las-certificaciones-elevadores-e-hidrogruas\\\/\"},\"author\":{\"name\":\"AXION | Elevadores &amp; Hidrogr\u00faas\",\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/#\\\/schema\\\/person\\\/acea9f5e5baf6f17d3bb576b786fd5c8\"},\"headline\":\"\u00bfCu\u00e1les son las certificaciones de nuestros elevadores e hidrogr\u00faas?\",\"datePublished\":\"2021-11-26T16:21:41+00:00\",\"dateModified\":\"2022-05-31T13:35:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/cuales-las-certificaciones-elevadores-e-hidrogruas\\\/\"},\"wordCount\":573,\"publisher\":{\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/cuales-las-certificaciones-elevadores-e-hidrogruas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/axionlift.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/20211126-Blog-Nota-CERTIFICACIONES.jpg\",\"articleSection\":[\"Fabricaci\u00f3n\",\"Innovaci\u00f3n\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/cuales-las-certificaciones-elevadores-e-hidrogruas\\\/\",\"url\":\"https:\\\/\\\/axionlift.com\\\/en\\\/cuales-las-certificaciones-elevadores-e-hidrogruas\\\/\",\"name\":\"\u00bfCu\u00e1les son las certificaciones de nuestros elevadores e hidrogr\u00faas?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/cuales-las-certificaciones-elevadores-e-hidrogruas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/cuales-las-certificaciones-elevadores-e-hidrogruas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/axionlift.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/20211126-Blog-Nota-CERTIFICACIONES.jpg\",\"datePublished\":\"2021-11-26T16:21:41+00:00\",\"dateModified\":\"2022-05-31T13:35:44+00:00\",\"description\":\"Nuestros elevadores e hidrogr\u00faas AXION est\u00e1n certificados por las normas de calidad internacionales ISO 9001\u00a0y\u00a0ANSI A92.2\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/cuales-las-certificaciones-elevadores-e-hidrogruas\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/axionlift.com\\\/en\\\/cuales-las-certificaciones-elevadores-e-hidrogruas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/cuales-las-certificaciones-elevadores-e-hidrogruas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/axionlift.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/20211126-Blog-Nota-CERTIFICACIONES.jpg\",\"contentUrl\":\"https:\\\/\\\/axionlift.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/20211126-Blog-Nota-CERTIFICACIONES.jpg\",\"width\":975,\"height\":500,\"caption\":\"Certificaciones elevadores e hidrogr\u00faas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/cuales-las-certificaciones-elevadores-e-hidrogruas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/axionlift.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfCu\u00e1les son las certificaciones de nuestros elevadores e hidrogr\u00faas?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/axionlift.com\\\/en\\\/\",\"name\":\"AxionLift - Elevadores & Hidrogr\u00faas\",\"description\":\"AxionLift - Una organizaci\u00f3n de alta performance\",\"publisher\":{\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/#organization\"},\"alternateName\":\"AxionLift\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/axionlift.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/#organization\",\"name\":\"AxionLift - Elevadores & Hidrogr\u00faas\",\"alternateName\":\"AxionLift\",\"url\":\"https:\\\/\\\/axionlift.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/axionlift.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/axion-mini.jpg\",\"contentUrl\":\"https:\\\/\\\/axionlift.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/axion-mini.jpg\",\"width\":320,\"height\":320,\"caption\":\"AxionLift - Elevadores & Hidrogr\u00faas\"},\"image\":{\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/axionlift.com\\\/en\\\/#\\\/schema\\\/person\\\/acea9f5e5baf6f17d3bb576b786fd5c8\",\"name\":\"AXION | Elevadores &amp; Hidrogr\u00faas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4bb0cdeb5f63fa57308758ad6e5d2366a845a65bbe64212fed18c0987756f646?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4bb0cdeb5f63fa57308758ad6e5d2366a845a65bbe64212fed18c0987756f646?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4bb0cdeb5f63fa57308758ad6e5d2366a845a65bbe64212fed18c0987756f646?s=96&d=mm&r=g\",\"caption\":\"AXION | Elevadores &amp; Hidrogr\u00faas\"},\"url\":\"https:\\\/\\\/axionlift.com\\\/en\\\/author\\\/axion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfCu\u00e1les son las certificaciones de nuestros elevadores e hidrogr\u00faas?","description":"Nuestros elevadores e hidrogr\u00faas AXION est\u00e1n certificados por las normas de calidad internacionales ISO 9001\u00a0y\u00a0ANSI A92.2","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/axionlift.com\/en\/cuales-las-certificaciones-elevadores-e-hidrogruas\/","og_locale":"en_GB","og_type":"article","og_title":"\u00bfCu\u00e1les son las certificaciones de nuestros elevadores e hidrogr\u00faas?","og_description":"Nuestros elevadores e hidrogr\u00faas AXION est\u00e1n certificados por las normas de calidad internacionales ISO 9001\u00a0y\u00a0ANSI A92.2","og_url":"https:\/\/axionlift.com\/en\/cuales-las-certificaciones-elevadores-e-hidrogruas\/","og_site_name":"AxionLift - Elevadores &amp; Hidrogr\u00faas","article_published_time":"2021-11-26T16:21:41+00:00","article_modified_time":"2022-05-31T13:35:44+00:00","og_image":[{"width":975,"height":500,"url":"https:\/\/axionlift.com\/wp-content\/uploads\/2021\/11\/20211126-Blog-Nota-CERTIFICACIONES.jpg","type":"image\/jpeg"}],"author":"AXION | Elevadores &amp; Hidrogr\u00faas","twitter_card":"summary_large_image","twitter_misc":{"Written by":"AXION | Elevadores &amp; Hidrogr\u00faas","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/axionlift.com\/en\/cuales-las-certificaciones-elevadores-e-hidrogruas\/#article","isPartOf":{"@id":"https:\/\/axionlift.com\/en\/cuales-las-certificaciones-elevadores-e-hidrogruas\/"},"author":{"name":"AXION | Elevadores &amp; Hidrogr\u00faas","@id":"https:\/\/axionlift.com\/en\/#\/schema\/person\/acea9f5e5baf6f17d3bb576b786fd5c8"},"headline":"\u00bfCu\u00e1les son las certificaciones de nuestros elevadores e hidrogr\u00faas?","datePublished":"2021-11-26T16:21:41+00:00","dateModified":"2022-05-31T13:35:44+00:00","mainEntityOfPage":{"@id":"https:\/\/axionlift.com\/en\/cuales-las-certificaciones-elevadores-e-hidrogruas\/"},"wordCount":573,"publisher":{"@id":"https:\/\/axionlift.com\/en\/#organization"},"image":{"@id":"https:\/\/axionlift.com\/en\/cuales-las-certificaciones-elevadores-e-hidrogruas\/#primaryimage"},"thumbnailUrl":"https:\/\/axionlift.com\/wp-content\/uploads\/2021\/11\/20211126-Blog-Nota-CERTIFICACIONES.jpg","articleSection":["Fabricaci\u00f3n","Innovaci\u00f3n"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/axionlift.com\/en\/cuales-las-certificaciones-elevadores-e-hidrogruas\/","url":"https:\/\/axionlift.com\/en\/cuales-las-certificaciones-elevadores-e-hidrogruas\/","name":"\u00bfCu\u00e1les son las certificaciones de nuestros elevadores e hidrogr\u00faas?","isPartOf":{"@id":"https:\/\/axionlift.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/axionlift.com\/en\/cuales-las-certificaciones-elevadores-e-hidrogruas\/#primaryimage"},"image":{"@id":"https:\/\/axionlift.com\/en\/cuales-las-certificaciones-elevadores-e-hidrogruas\/#primaryimage"},"thumbnailUrl":"https:\/\/axionlift.com\/wp-content\/uploads\/2021\/11\/20211126-Blog-Nota-CERTIFICACIONES.jpg","datePublished":"2021-11-26T16:21:41+00:00","dateModified":"2022-05-31T13:35:44+00:00","description":"Nuestros elevadores e hidrogr\u00faas AXION est\u00e1n certificados por las normas de calidad internacionales ISO 9001\u00a0y\u00a0ANSI A92.2","breadcrumb":{"@id":"https:\/\/axionlift.com\/en\/cuales-las-certificaciones-elevadores-e-hidrogruas\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/axionlift.com\/en\/cuales-las-certificaciones-elevadores-e-hidrogruas\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/axionlift.com\/en\/cuales-las-certificaciones-elevadores-e-hidrogruas\/#primaryimage","url":"https:\/\/axionlift.com\/wp-content\/uploads\/2021\/11\/20211126-Blog-Nota-CERTIFICACIONES.jpg","contentUrl":"https:\/\/axionlift.com\/wp-content\/uploads\/2021\/11\/20211126-Blog-Nota-CERTIFICACIONES.jpg","width":975,"height":500,"caption":"Certificaciones elevadores e hidrogr\u00faas"},{"@type":"BreadcrumbList","@id":"https:\/\/axionlift.com\/en\/cuales-las-certificaciones-elevadores-e-hidrogruas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/axionlift.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfCu\u00e1les son las certificaciones de nuestros elevadores e hidrogr\u00faas?"}]},{"@type":"WebSite","@id":"https:\/\/axionlift.com\/en\/#website","url":"https:\/\/axionlift.com\/en\/","name":"AxionLift - Elevadores & Hidrogr\u00faas","description":"AxionLift - Una organizaci\u00f3n de alta performance","publisher":{"@id":"https:\/\/axionlift.com\/en\/#organization"},"alternateName":"AxionLift","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/axionlift.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/axionlift.com\/en\/#organization","name":"AxionLift - Elevadores & Hidrogr\u00faas","alternateName":"AxionLift","url":"https:\/\/axionlift.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/axionlift.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/axionlift.com\/wp-content\/uploads\/2024\/08\/axion-mini.jpg","contentUrl":"https:\/\/axionlift.com\/wp-content\/uploads\/2024\/08\/axion-mini.jpg","width":320,"height":320,"caption":"AxionLift - Elevadores & Hidrogr\u00faas"},"image":{"@id":"https:\/\/axionlift.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/axionlift.com\/en\/#\/schema\/person\/acea9f5e5baf6f17d3bb576b786fd5c8","name":"AXION | Elevadores &amp; Hidrogr\u00faas","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/4bb0cdeb5f63fa57308758ad6e5d2366a845a65bbe64212fed18c0987756f646?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4bb0cdeb5f63fa57308758ad6e5d2366a845a65bbe64212fed18c0987756f646?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4bb0cdeb5f63fa57308758ad6e5d2366a845a65bbe64212fed18c0987756f646?s=96&d=mm&r=g","caption":"AXION | Elevadores &amp; Hidrogr\u00faas"},"url":"https:\/\/axionlift.com\/en\/author\/axion\/"}]}},"_links":{"self":[{"href":"https:\/\/axionlift.com\/en\/wp-json\/wp\/v2\/posts\/2016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axionlift.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/axionlift.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/axionlift.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/axionlift.com\/en\/wp-json\/wp\/v2\/comments?post=2016"}],"version-history":[{"count":4,"href":"https:\/\/axionlift.com\/en\/wp-json\/wp\/v2\/posts\/2016\/revisions"}],"predecessor-version":[{"id":3305,"href":"https:\/\/axionlift.com\/en\/wp-json\/wp\/v2\/posts\/2016\/revisions\/3305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/axionlift.com\/en\/wp-json\/wp\/v2\/media\/2363"}],"wp:attachment":[{"href":"https:\/\/axionlift.com\/en\/wp-json\/wp\/v2\/media?parent=2016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/axionlift.com\/en\/wp-json\/wp\/v2\/categories?post=2016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/axionlift.com\/en\/wp-json\/wp\/v2\/tags?post=2016"},{"taxonomy":"wf_post_folders","embeddable":true,"href":"https:\/\/axionlift.com\/en\/wp-json\/wp\/v2\/wf_post_folders?post=2016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}